{"id":9182,"date":"2024-11-13T15:53:27","date_gmt":"2024-11-13T14:53:27","guid":{"rendered":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/"},"modified":"2026-04-13T11:48:17","modified_gmt":"2026-04-13T09:48:17","slug":"suporte-de-placa-agilite-sub-zero","status":"publish","type":"product","link":"https:\/\/mssdefence.com\/pt\/product\/agilite-sub-zero-plate-carrier\/","title":{"rendered":"Suporte de placa Agilite Sub-Zero | Agilite | MSS Defence"},"content":{"rendered":"<div>\n<h1 style=\"margin: 0 0 16px 0\"><strong>Suporte de placa Agilite Sub-Zero - Body Armour<span style=\"color: #ff0000\">.<\/span><\/strong><\/h1>\n<p style=\"margin: 0 0 16px 0\"><strong>O suporte de placas Agilite Sub-Zero<\/strong> \u00e9 um colete \u00e0 prova de bala com uma distribui\u00e7\u00e3o de peso em V e constru\u00e7\u00e3o em CORDURA 500D, fabricado pela Agilite em Israel. Foi concebido para uma utiliza\u00e7\u00e3o r\u00e1pida e dissimulada, oferecendo conforto e versatilidade ao pessoal militar e \u00e0s equipas de interven\u00e7\u00e3o.<\/p>\n<h5 style=\"margin: 0 0 8px 0\"><strong>Vis\u00e3o geral operacional:<\/strong><\/h5>\n<p style=\"margin: 0 0 16px 0\"><strong>O suporte de placas Agilite Sub-Zero<\/strong> utiliza um sistema de distribui\u00e7\u00e3o de peso com design em V, distribuindo a carga por oito pontos de suspens\u00e3o para evitar pontos de press\u00e3o durante o uso prolongado. A cinta el\u00e1stica modular inclui tr\u00eas c\u00e9lulas de cada lado para armazenamento seguro de carregadores, r\u00e1dios e outros equipamentos. O saco de placa traseiro \u00e9 compat\u00edvel com placas para uma personaliza\u00e7\u00e3o r\u00e1pida e o seu design ventilado afasta o suor, mantendo o conforto em situa\u00e7\u00f5es de alta intensidade.<\/p>\n<h5 style=\"margin: 0 0 8px 0\"><strong>Aplica\u00e7\u00f5es:<\/strong><\/h5>\n<ul style=\"margin: 0 0 16px 20px;padding: 0\">\n<li style=\"margin: 0 0 6px 0\">Opera\u00e7\u00f5es militares que exigem uma proje\u00e7\u00e3o r\u00e1pida<\/li>\n<li style=\"margin: 0 0 6px 0\">Miss\u00f5es t\u00e1cticas de aplica\u00e7\u00e3o da lei<\/li>\n<li style=\"margin: 0 0 6px 0\">Cen\u00e1rios de emerg\u00eancia para socorristas<\/li>\n<li style=\"margin: 0 0 6px 0\">Exerc\u00edcios de forma\u00e7\u00e3o em ambientes de alta temperatura<\/li>\n<li style=\"margin: 0\">Opera\u00e7\u00f5es secretas que necessitam de equipamento discreto<\/li>\n<\/ul>\n<h5 style=\"margin: 0 0 8px 0\"><strong>Caracter\u00edsticas principais:<\/strong><\/h5>\n<ul style=\"margin: 0 0 16px 20px;padding: 0\">\n<li style=\"margin: 0 0 6px 0\"><strong>Conce\u00e7\u00e3o em V Distribui\u00e7\u00e3o do peso:<\/strong> Distribui a carga por 8 pontos para maior conforto<\/li>\n<li style=\"margin: 0 0 6px 0\"><strong>Faixa de cintura el\u00e1stica modular:<\/strong> Personaliz\u00e1vel com tr\u00eas c\u00e9lulas por lado<\/li>\n<li style=\"margin: 0 0 6px 0\"><strong>Compatibilidade com placas de sinaliza\u00e7\u00e3o:<\/strong> Suporta Agilite Molle Placard e outros<\/li>\n<li style=\"margin: 0 0 6px 0\"><strong>Arrefecimento Ventila\u00e7\u00e3o:<\/strong> As \u00e1reas ventiladas absorvem o suor para controlo da temperatura<\/li>\n<li style=\"margin: 0 0 6px 0\"><strong>Acomoda\u00e7\u00e3o do tamanho da placa:<\/strong> Adapta-se a placas de corte SAPI, ESAPI, Shooter's e Swimmer's m\u00e9dias e grandes<\/li>\n<li style=\"margin: 0 0 6px 0\"><strong>500D CORDURA Constru\u00e7\u00e3o:<\/strong> Dur\u00e1vel e leve, com 1,26 lbs<\/li>\n<li style=\"margin: 0\"><strong>Pain\u00e9is MOLLE de velcro cortados a laser:<\/strong> Para personaliza\u00e7\u00e3o adicional<\/li>\n<\/ul>\n<h5 style=\"margin: 0 0 8px 0\"><strong>Agilite - Fabricante:<\/strong><\/h5>\n<p style=\"margin: 0 0 20px 0\">A Agilite \u00e9 uma empresa sediada em Israel, especializada em equipamento t\u00e1tico e solu\u00e7\u00f5es de blindagem corporal. Conhecidos pelos seus designs inovadores e materiais dur\u00e1veis, os produtos Agilite s\u00e3o utilizados por militares e ag\u00eancias de aplica\u00e7\u00e3o da lei em todo o mundo.<\/p>\n<hr style=\"margin: 0 0 20px 0\" \/>\n<h3 style=\"margin: 0 0 12px 0\"><strong>Perguntas mais frequentes<span style=\"color: #ff0000\">.<\/span><\/strong><\/h3>\n<ol style=\"margin: 0 0 24px 0;padding-left: 20px\">\n<li style=\"margin: 0 0 16px 0\">\n    <strong>Qual \u00e9 o peso do suporte de placas Agilite Sub-Zero?<\/strong><br \/>\n    <strong>O suporte de placas Agilite Sub-Zero<\/strong> pesa 0,57 kg (1,26 lbs), o que o torna uma op\u00e7\u00e3o leve para uma utiliza\u00e7\u00e3o prolongada.\n  <\/li>\n<li style=\"margin: 0 0 16px 0\">\n    <strong>Quais os tamanhos de placa que o suporte pode acomodar?<\/strong><br \/>\n    O suporte adapta-se a placas de corte SAPI, ESAPI, Shooter's e Swimmer's m\u00e9dias e grandes, assegurando uma prote\u00e7\u00e3o vers\u00e1til.\n  <\/li>\n<li style=\"margin: 0 0 16px 0\">\n    <strong>O suporte \u00e9 compat\u00edvel com outras placas?<\/strong><br \/>\n    Sim, o saco para placa traseira \u00e9 compat\u00edvel com placards, permitindo uma personaliza\u00e7\u00e3o r\u00e1pida com o Agilite Molle Placard ou outros placards.\n  <\/li>\n<li style=\"margin: 0 0 16px 0\">\n    <strong>Como funciona a ventila\u00e7\u00e3o de arrefecimento?<\/strong><br \/>\n    O porta-avi\u00f5es possui \u00e1reas ventiladas que absorvem o suor, mantendo o utilizador fresco durante situa\u00e7\u00f5es de alta intensidade ou treino.\n  <\/li>\n<li style=\"margin: 0 0 16px 0\">\n    <strong>Que materiais s\u00e3o utilizados na constru\u00e7\u00e3o?<\/strong><br \/>\n    O porta-objectos \u00e9 fabricado em 500D CORDURA Mil Spec Tactical Nylon, garantindo durabilidade e resist\u00eancia ao desgaste.\n  <\/li>\n<li style=\"margin: 0 0 16px 0\">\n    <strong>A faixa de cintura pode ser personalizada?<\/strong><br \/>\n    Sim, a cinta el\u00e1stica modular inclui tr\u00eas c\u00e9lulas de cada lado para guardar carregadores, r\u00e1dios e outros equipamentos.\n  <\/li>\n<li style=\"margin: 0\">\n    <strong>Onde \u00e9 fabricado o suporte de placas Agilite Sub-Zero?<\/strong><br \/>\n    <strong>O suporte de placas Agilite Sub-Zero<\/strong> \u00e9 fabricado pela Agilite em Israel.\n  <\/li>\n<\/ol>\n<p><iframe title=\"O porta-placas de Israel DECLASSIFICADO!\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/BXSJxvt0Ylk?start=2&amp;feature=oembed\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>O suporte de placas Agilite Sub-Zero<\/strong> \u00e9 um colete \u00e0 prova de bala concebido para militares e pessoal de primeira interven\u00e7\u00e3o. Fabricado pela Agilite, apresenta uma distribui\u00e7\u00e3o de peso com design em V e uma constru\u00e7\u00e3o em CORDURA 500D.<\/p>","protected":false},"featured_media":9184,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[170,58],"product_tag":[],"class_list":["post-9182","product","type-product","status-publish","has-post-thumbnail","product_cat-body-armour-gear","product_cat-protection","pa_brand-agilite","first","instock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence | MSS Defence<\/title>\n<meta name=\"description\" content=\"The Agilite Sub-Zero Plate Carrier for military and first responders. V-design \u00b7 500D CORDURA \u00b7 1.26 lbs weight. Enquire at MSS Defence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mssdefence.com\/pt\/produto\/suporte-de-placa-agilite-sub-zero\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence | MSS Defence\" \/>\n<meta property=\"og:description\" content=\"The Agilite Sub-Zero Plate Carrier for military and first responders. V-design \u00b7 500D CORDURA \u00b7 1.26 lbs weight. Enquire at MSS Defence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mssdefence.com\/pt\/produto\/suporte-de-placa-agilite-sub-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"MSS Defence\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T09:48:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mssdefence.com\/wp-content\/uploads\/2024\/11\/132_aa.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/\",\"url\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/\",\"name\":\"Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence | MSS Defence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mssdefence.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mssdefence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/132_aa.webp\",\"datePublished\":\"2024-11-13T14:53:27+00:00\",\"dateModified\":\"2026-04-13T09:48:17+00:00\",\"description\":\"The Agilite Sub-Zero Plate Carrier for military and first responders. V-design \u00b7 500D CORDURA \u00b7 1.26 lbs weight. Enquire at MSS Defence.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mssdefence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/132_aa.webp\",\"contentUrl\":\"https:\\\/\\\/mssdefence.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/132_aa.webp\",\"width\":1500,\"height\":1500,\"caption\":\"Agilite Sub-Zero Plate Carrier front view, olive green, shoulder straps visible.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mssdefence.com\\\/product\\\/agilite-sub-zero-plate-carrier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mssdefence.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue NEW\",\"item\":\"https:\\\/\\\/mssdefence.com\\\/catalogue-new\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mssdefence.com\\\/#website\",\"url\":\"https:\\\/\\\/mssdefence.com\\\/\",\"name\":\"MSS Defence\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mssdefence.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porta-placas Agilite Sub-Zero | Agilite | MSS Defence | MSS Defence","description":"O porta-placas Agilite Sub-Zero para militares e socorristas. Design em V - 500D CORDURA - 1.26 lbs de peso. Consultar a MSS Defence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mssdefence.com\/pt\/produto\/suporte-de-placa-agilite-sub-zero\/","og_locale":"pt_PT","og_type":"article","og_title":"Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence | MSS Defence","og_description":"The Agilite Sub-Zero Plate Carrier for military and first responders. V-design \u00b7 500D CORDURA \u00b7 1.26 lbs weight. Enquire at MSS Defence.","og_url":"https:\/\/mssdefence.com\/pt\/produto\/suporte-de-placa-agilite-sub-zero\/","og_site_name":"MSS Defence","article_modified_time":"2026-04-13T09:48:17+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/mssdefence.com\/wp-content\/uploads\/2024\/11\/132_aa.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/","url":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/","name":"Porta-placas Agilite Sub-Zero | Agilite | MSS Defence | MSS Defence","isPartOf":{"@id":"https:\/\/mssdefence.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/#primaryimage"},"image":{"@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/#primaryimage"},"thumbnailUrl":"https:\/\/mssdefence.com\/wp-content\/uploads\/2024\/11\/132_aa.webp","datePublished":"2024-11-13T14:53:27+00:00","dateModified":"2026-04-13T09:48:17+00:00","description":"O porta-placas Agilite Sub-Zero para militares e socorristas. Design em V - 500D CORDURA - 1.26 lbs de peso. Consultar a MSS Defence.","breadcrumb":{"@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/#primaryimage","url":"https:\/\/mssdefence.com\/wp-content\/uploads\/2024\/11\/132_aa.webp","contentUrl":"https:\/\/mssdefence.com\/wp-content\/uploads\/2024\/11\/132_aa.webp","width":1500,"height":1500,"caption":"Agilite Sub-Zero Plate Carrier front view, olive green, shoulder straps visible."},{"@type":"BreadcrumbList","@id":"https:\/\/mssdefence.com\/product\/agilite-sub-zero-plate-carrier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mssdefence.com\/"},{"@type":"ListItem","position":2,"name":"Catalogue NEW","item":"https:\/\/mssdefence.com\/catalogue-new\/"},{"@type":"ListItem","position":3,"name":"Agilite Sub-Zero Plate Carrier | Agilite | MSS Defence"}]},{"@type":"WebSite","@id":"https:\/\/mssdefence.com\/#website","url":"https:\/\/mssdefence.com\/","name":"MSS Defesa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mssdefence.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/product\/9182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/comments?post=9182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/media\/9184"}],"wp:attachment":[{"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/media?parent=9182"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/product_brand?post=9182"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/product_cat?post=9182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mssdefence.com\/pt\/wp-json\/wp\/v2\/product_tag?post=9182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}